{"id":226,"date":"2017-01-18T09:35:19","date_gmt":"2017-01-18T08:35:19","guid":{"rendered":"http:\/\/www.etoile-on.com\/site\/?page_id=226"},"modified":"2018-11-20T13:21:10","modified_gmt":"2018-11-20T12:21:10","slug":"e-tm-gestione-gare-ospedaliere","status":"publish","type":"page","link":"https:\/\/www.etoile-on.com\/site\/index.php\/e-tm-gestione-gare-ospedaliere\/","title":{"rendered":"E-TM Gestione Gare Ospedaliere"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; background_color=&#8221;#58595b&#8221; custom_padding=&#8221;0px|0px|28px|0px&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.0.71&#8243; parallax=&#8221;on&#8221;][et_pb_row custom_padding=&#8221;0px|0px|16px|0px&#8221; admin_label=&#8221;row&#8221; _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_divider height=&#8221;60&#8243; admin_label=&#8221;Divider&#8221; _builder_version=&#8221;3.0.47&#8243;] [\/et_pb_divider][et_pb_text background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Text&#8221; _builder_version=&#8221;3.0.71&#8243; header_text_color=&#8221;#00AEEF&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<h1 style=\"font-size: 52px;\">E-TM<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.71&#8243; header_font_size=&#8221;43px&#8221; header_text_color=&#8221;#ffffff&#8221;]<\/p>\n<h1><\/h1>\n<h1 style=\"text-align: center;\">Tender Management<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_blurb title=&#8221;Fascicolo di Gara&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue086&#8221; icon_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;3.0.71&#8243; header_font=&#8221;|on|||&#8221; header_font_size=&#8221;20px&#8221; header_text_color=&#8221;#00AEEF&#8221; body_font=&#8221;||||&#8221; body_font_size=&#8221;14px&#8221; body_text_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Il sistema permette di creare per ogni Gara un fascicolo contenente i dati di bando, i lotti, i prodotti, le note ed i documenti associati.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_blurb title=&#8221;Generazione Documenti di Gara&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue059&#8221; icon_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;3.0.71&#8243; header_font=&#8221;|on|||&#8221; header_font_size=&#8221;20px&#8221; header_text_color=&#8221;#00aeef&#8221; body_font=&#8221;||||&#8221; body_text_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Il documento di Offerta\u00a0e le Lettere Commerciali sono generate automaticamente dal sistema sulla base di template pre-configurati.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_blurb title=&#8221;Scadenze di Gara&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue023&#8221; icon_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;3.0.71&#8243; header_font=&#8221;|on|||&#8221; header_font_size=&#8221;20&#8243; header_text_color=&#8221;#00AEEF&#8221; body_font=&#8221;||||&#8221; body_text_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Il sistema di notifiche e alert consente di configurare ogni genere di scadenza relativa al procedimento di Gara.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_blurb title=&#8221;Lotti ed Esiti di Gara&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue0ff&#8221; icon_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;3.0.71&#8243; header_font=&#8221;|on|||&#8221; header_font_size=&#8221;20px&#8221; header_text_color=&#8221;#00AEEF&#8221; body_text_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>La gestione dei Lotti permette di tenere traccia dei singoli esiti di aggiudicazione sia della propria azienda che della concorrenza.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_blurb title=&#8221;Prezzi  e Scontistica di Gara&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue0da&#8221; icon_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;3.0.71&#8243; header_font=&#8221;|on|||&#8221; header_font_size=&#8221;20&#8243; header_text_color=&#8221;#00AEEF&#8221; body_text_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>L&#8217;anagrafica dei Prodotti ed i prezzi per cliente sono interfacciati con l&#8217;ERP aziendale\u00a0e la scontistica pu\u00f2 essere calcolata secondo algoritmi configurabili.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_blurb title=&#8221;Report&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue029&#8221; icon_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;3.0.71&#8243; header_font=&#8221;|on|||&#8221; header_font_size=&#8221;20px&#8221; header_text_color=&#8221;#00AEEF&#8221; body_text_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Tutti i dati del sistema, relativi a prodotti, gare, aree geografiche, etc&#8230;, sono interrogabili tramite report dinamici e interattivi.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding=&#8221;54px|0px|14px|0px&#8221; _builder_version=&#8221;3.0.71&#8243;][et_pb_row _builder_version=&#8221;3.0.71&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.71&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_contact_form title=&#8221;Vuoi saperne di pi\u00f9? Prenotare una demo? &#8221; submit_button_text=&#8221;Contattatemi&#8221; module_id=&#8221;et_pb_contact_form_0&#8243; _builder_version=&#8221;3.0.71&#8243; title_font_size=&#8221;37px&#8221; title_text_color=&#8221;#00AEEF&#8221; form_field_text_color=&#8221;#58595B&#8221; custom_button=&#8221;on&#8221; button_icon=&#8221;%%277%%&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Nome&#8221; field_background_color=&#8221;#C7EAFB&#8221; _builder_version=&#8221;3.0.47&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Indirizzo e-mail&#8221; field_type=&#8221;email&#8221; field_background_color=&#8221;#C7EAFB&#8221; _builder_version=&#8221;3.0.47&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Field_3&#8243; field_title=&#8221;Ruolo \/ Azienda (Facoltativo)&#8221; required_mark=&#8221;off&#8221; field_background_color=&#8221;#C7EAFB&#8221; _builder_version=&#8221;3.0.71&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Field_4&#8243; field_title=&#8221;Telefono (Facoltativo)&#8221; required_mark=&#8221;off&#8221; field_background_color=&#8221;#C7EAFB&#8221; _builder_version=&#8221;3.0.71&#8243;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; fullwidth=&#8221;on&#8221; _builder_version=&#8221;3.0.71&#8243;][et_pb_fullwidth_slider _builder_version=&#8221;3.0.71&#8243; custom_button=&#8221;on&#8221; button_icon_color=&#8221;#00AEEF&#8221;][et_pb_slide background_image=&#8221;http:\/\/www.etoile-on.com\/site\/wp-content\/uploads\/2017\/09\/bruchure-3330.gif&#8221; arrows_custom_color=&#8221;#00AEEF&#8221; _builder_version=&#8221;3.0.71&#8243;][\/et_pb_slide][et_pb_slide background_image=&#8221;http:\/\/www.etoile-on.com\/site\/wp-content\/uploads\/2017\/09\/brochure-desc-b-b.png&#8221; arrows_custom_color=&#8221;#00AEEF&#8221; _builder_version=&#8221;3.0.71&#8243;][\/et_pb_slide][et_pb_slide background_image=&#8221;http:\/\/www.etoile-on.com\/site\/wp-content\/uploads\/2017\/09\/brochure-TM-grey2.png&#8221; arrows_custom_color=&#8221;#00AEEF&#8221; _builder_version=&#8221;3.0.71&#8243;][\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-TM Tender ManagementIl sistema permette di creare per ogni Gara un fascicolo contenente i dati di bando, i lotti, i prodotti, le note ed i documenti associati.Il documento di Offerta\u00a0e le Lettere Commerciali sono generate automaticamente dal sistema sulla base di template pre-configurati.Il sistema di notifiche e alert consente di configurare ogni genere di scadenza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_exactmetrics_skip_tracking":false},"_links":{"self":[{"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/pages\/226"}],"collection":[{"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/comments?post=226"}],"version-history":[{"count":40,"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/pages\/226\/revisions"}],"predecessor-version":[{"id":25007,"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/pages\/226\/revisions\/25007"}],"wp:attachment":[{"href":"https:\/\/www.etoile-on.com\/site\/index.php\/wp-json\/wp\/v2\/media?parent=226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}